{"id":1777,"date":"2021-05-18T14:42:53","date_gmt":"2021-05-18T18:42:53","guid":{"rendered":"https:\/\/www.citedelenergie.com\/activites\/city-tour\/"},"modified":"2021-07-13T11:34:59","modified_gmt":"2021-07-13T15:34:59","slug":"city-tour","status":"publish","type":"activites","link":"https:\/\/www.citedelenergie.com\/en\/activites\/city-tour\/","title":{"rendered":"City Tour"},"content":{"rendered":"<div id=\"zone-block_5e31e4d7d6bdd\" class=\"section section--default md-0\">\r\n\t<div class=\"py-2 py-md-3 section-placeholder\">\r\n\t\t\t\t\t\t<div class=\"section-placeholder__inner js-placeholder\">\r\n\t\t\t\t\t<div class=\"placeholder js-placeholder__inner\">City Tour<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"container reveal js-reveal\">\n\t<div class=\"row\">\n\t\t\t\t<div class=\"overflow-hidden col-12\">\n\t\t\t\t\t<div class=\"overflow-hidden text-left\">\r\n\t\t\t<span class=\"section-subtitle reveal__item\" data-reveal=\"opacity translatexr\" data-reveal-delay=\"x\">la Cit\u00e9 de l&#8217;\u00c9nergie<\/span>\r\n\t\t\t<h1 class=\"reveal__item section-title\" data-reveal=\"opacity translatexr\" data-reveal-delay=\"x\">City Tour<\/h1>\r\n\t\t<\/div>\r\n\t\t\t\t\t<div class=\"md-3 zone-content reveal__item\" data-reveal=\"opacity translatexr\" data-reveal-delay=\"x\">\n\t\t\t\t<p>* Reserve your place via our <a href=\"https:\/\/billetterie.citedelenergie.com\/reservation\/etape-1\/etape-1.php\">online ticketing<\/a><\/p>\n<p>La Cit\u00e9 de l&#8217;\u00e9nergie offers you a guided tour of Shawinigan aboard a tramway-style bus. You will discover the many facets of Shawinigan&#8217;s history, its architectural treasures, its surprising anecdotes, its various neighborhoods and its magnificent urban development.<\/p>\n<p><em>Duration: 1 hour and 15 minutes<\/em><\/p>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\" md-2\">\r\n\t\t\t\t\t\t\t\t<a class=\"btn btn--half\" href=\"https:\/\/www.citedelenergie.com\/planifiez-votre-visite\/\" target=\"\">\r\n\t\t\t\t\t\t<span class=\"inner-text\">Plan your visit<span class=\"inner-text__placeholder\">Plan your visit<\/span><\/span>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\r\n<\/div>\n\n<div id=\"prices-block_5e31e4ead6bde\" class=\"section section--primary md-0 bg-side\">\r\n\t<div class=\"py-2 py-md-3 section-placeholder\">\r\n\t\t\t\t\t\t<div class=\"section-placeholder__inner js-placeholder\">\r\n\t\t\t\t\t<div class=\"placeholder js-placeholder__inner\">Schedules and Rates<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"container\">\r\n\t<div class=\"reveal js-reveal\">\r\n\t\t\t\t<h2 id=\"schedules-and-rates\" class=\"overflow-hidden text-center -is-anchor\">\r\n\t\t\t<span class=\"section-subtitle reveal__item\" data-reveal=\"opacity translatexr\" data-reveal-delay=\"x\">la Cit\u00e9 de l&#8217;\u00c9nergie<\/span>\r\n\t\t\t<span class=\"reveal__item section-title\" data-reveal=\"opacity translatexr\" data-reveal-delay=\"x\">Schedules and Rates<\/span>\r\n\t\t<\/h2>\r\n\t\t\t<\/div>\r\n\t<div class=\"md-3 md-md-4 md-lg-5 md-xl-6\">\r\n\t\t\t\t\t\t<div class=\"reveal js-reveal md-6\">\r\n\t\t\t\t\t<div class=\"text-center\">\r\n\t\t\t\t\t\t<div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"reveal__item\" data-reveal=\"opacity translatexr\" data-reveal-delay=\"x\">\u00e0 la carte<\/h3>\r\n\t\t\t\t\t\t\t\t\t<p class=\" md-0 reveal__item\" data-reveal=\"opacity translatexr\" data-reveal-delay=\"x\">Until September 26, 2021<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"reveal__item\" data-reveal=\"opacity translatexr\" data-reveal-delay=\"x\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"md-2\">\r\n\t\t\t\t\t\t<ul class=\"prices\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"price reveal__item\" data-reveal=\"opacity translatexr\" data-reveal-delay=\"x\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"price__inner\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"price__title\">Adult<\/h4>\r\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"price__age\">(13 years and older)<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"price__value\">$16<\/p>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"price reveal__item\" data-reveal=\"opacity translatexr\" data-reveal-delay=\"x\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"price__inner\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"price__title\">Child<\/h4>\r\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"price__age\">(6 to 12 years)<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"price__value\">$10<\/p>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"price reveal__item\" data-reveal=\"opacity translatexr\" data-reveal-delay=\"x\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"price__inner\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"price__title\">Family<\/h4>\r\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"price__age\">(2 adults and 1 child from 6 to 12 years)<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"price__value\">$40<\/p>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"price reveal__item\" data-reveal=\"opacity translatexr\" data-reveal-delay=\"x\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"price__inner\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"price__title\">Family<\/h4>\r\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"price__age\">(2 adults and 2 or 3 children 6 to 12 years)<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"price__value\">$45<\/p>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"md-2 text-center reveal__item\" data-reveal=\"opacity translatexr\" data-reveal-delay=\"x\">\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n<\/div>\r\n\t<\/div>\r\n<\/div>\n\n<div id=\"gallery-block_5e31e5d6d6be3\" class=\"section section--default md-0\">\r\n\t<div class=\"py-2 py-md-3 section-placeholder\">\r\n\t\t\t\t\t\t<div class=\"section-placeholder__inner js-placeholder\">\r\n\t\t\t\t\t<div class=\"placeholder js-placeholder__inner\">Images<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"container reveal js-reveal\">\r\n\t\t\t<h2 id=\"images\" class=\"overflow-hidden text-left -is-anchor\">\r\n\t\t\t<span class=\"section-subtitle reveal__item\" data-reveal=\"opacity translatexr\" data-reveal-delay=\"x\">la Cit\u00e9 de l&#8217;\u00c9nergie<\/span>\r\n\t\t\t<span class=\"reveal__item section-title\" data-reveal=\"opacity translatexr\" data-reveal-delay=\"x\">Images<\/span>\r\n\t\t<\/h2>\r\n\t\t\t<div class=\"md-3\">\r\n\t\t<div class=\"gallery-slider\">\r\n\t\t\t\t\t\t\t\t<a href=\"\/wp-content\/uploads\/2021\/06\/Tour-de-ville-2-scaled-1.jpg\" data-fancybox=\"gallery\"><img decoding=\"async\" src=\"\/resize?src=\/wp-content\/uploads\/2021\/06\/Tour-de-ville-2-scaled-1.jpg&#038;w=1640&#038;h=865\" alt=\"Visite guid\u00e9e de la ville de Shawinigan \u00e0 bord d\u2019un autobus de style tramway\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t\t\t\t\t<a href=\"\/wp-content\/uploads\/2021\/06\/Tour-de-ville-1-scaled-1.jpg\" data-fancybox=\"gallery\"><img decoding=\"async\" src=\"\/resize?src=\/wp-content\/uploads\/2021\/06\/Tour-de-ville-1-scaled-1.jpg&#038;w=1640&#038;h=865\" alt=\"Visite guid\u00e9e de la ville de Shawinigan \u00e0 bord d\u2019un autobus de style tramway (2)\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n\t<\/div>\r\n<\/div>","protected":false},"featured_media":3040,"template":"","activites_categories":[25],"class_list":["post-1777","activites","type-activites","status-publish","has-post-thumbnail","hentry","activites_categories-other-activities"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>City Tour - Cit\u00e9 de l&#039;\u00c9nergie<\/title>\n<meta name=\"description\" content=\"What to visit in Shawinigan? - La Cit\u00e9 de l&#039;\u00e9nergie offers you a guided tour of Shawinigan aboard a tramway-style bus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.citedelenergie.com\/en\/activites\/city-tour\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"City Tour - Cit\u00e9 de l&#039;\u00c9nergie\" \/>\n<meta property=\"og:description\" content=\"What to visit in Shawinigan? - La Cit\u00e9 de l&#039;\u00e9nergie offers you a guided tour of Shawinigan aboard a tramway-style bus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.citedelenergie.com\/en\/activites\/city-tour\/\" \/>\n<meta property=\"og:site_name\" content=\"La Cit\u00e9 de l&#039;\u00c9nergie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/citedelenergie\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-13T15:34:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.citedelenergie.com\/wp-content\/uploads\/2021\/06\/Tour-de-ville-1-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1792\" \/>\n\t<meta property=\"og:image:height\" content=\"1009\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@citedelenergie\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/activites\\\/city-tour\\\/\",\"url\":\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/activites\\\/city-tour\\\/\",\"name\":\"City Tour - Cit\u00e9 de l'\u00c9nergie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/activites\\\/city-tour\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/activites\\\/city-tour\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.citedelenergie.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Tour-de-ville-1-scaled-1.jpg\",\"datePublished\":\"2021-05-18T18:42:53+00:00\",\"dateModified\":\"2021-07-13T15:34:59+00:00\",\"description\":\"What to visit in Shawinigan? - La Cit\u00e9 de l'\u00e9nergie offers you a guided tour of Shawinigan aboard a tramway-style bus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/activites\\\/city-tour\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/activites\\\/city-tour\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/activites\\\/city-tour\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.citedelenergie.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Tour-de-ville-1-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.citedelenergie.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Tour-de-ville-1-scaled-1.jpg\",\"width\":1792,\"height\":1009,\"caption\":\"Visite guid\u00e9e de la ville de Shawinigan \u00e0 bord d\u2019un autobus de style tramway (2)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/activites\\\/city-tour\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"City Tour\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/\",\"name\":\"La Cit\u00e9 de l'\u00c9nergie\",\"description\":\"Expositions &amp; Activit\u00e9s Immersives\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/#organization\",\"name\":\"La Cit\u00e9 de l'\u00c9nergie\",\"url\":\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.citedelenergie.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-Cite-fond-mauve-2.png\",\"contentUrl\":\"https:\\\/\\\/www.citedelenergie.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-Cite-fond-mauve-2.png\",\"width\":762,\"height\":700,\"caption\":\"La Cit\u00e9 de l'\u00c9nergie\"},\"image\":{\"@id\":\"https:\\\/\\\/www.citedelenergie.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/citedelenergie\\\/\",\"https:\\\/\\\/x.com\\\/citedelenergie\",\"https:\\\/\\\/www.instagram.com\\\/citedelenergie\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqe6ukCAPaHxd8osxT7eLIA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"City Tour - Cit\u00e9 de l'\u00c9nergie","description":"What to visit in Shawinigan? - La Cit\u00e9 de l'\u00e9nergie offers you a guided tour of Shawinigan aboard a tramway-style bus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.citedelenergie.com\/en\/activites\/city-tour\/","og_locale":"en_US","og_type":"article","og_title":"City Tour - Cit\u00e9 de l'\u00c9nergie","og_description":"What to visit in Shawinigan? - La Cit\u00e9 de l'\u00e9nergie offers you a guided tour of Shawinigan aboard a tramway-style bus.","og_url":"https:\/\/www.citedelenergie.com\/en\/activites\/city-tour\/","og_site_name":"La Cit\u00e9 de l&#039;\u00c9nergie","article_publisher":"https:\/\/www.facebook.com\/citedelenergie\/","article_modified_time":"2021-07-13T15:34:59+00:00","og_image":[{"width":1792,"height":1009,"url":"https:\/\/www.citedelenergie.com\/wp-content\/uploads\/2021\/06\/Tour-de-ville-1-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@citedelenergie","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.citedelenergie.com\/en\/activites\/city-tour\/","url":"https:\/\/www.citedelenergie.com\/en\/activites\/city-tour\/","name":"City Tour - Cit\u00e9 de l'\u00c9nergie","isPartOf":{"@id":"https:\/\/www.citedelenergie.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.citedelenergie.com\/en\/activites\/city-tour\/#primaryimage"},"image":{"@id":"https:\/\/www.citedelenergie.com\/en\/activites\/city-tour\/#primaryimage"},"thumbnailUrl":"https:\/\/www.citedelenergie.com\/wp-content\/uploads\/2021\/06\/Tour-de-ville-1-scaled-1.jpg","datePublished":"2021-05-18T18:42:53+00:00","dateModified":"2021-07-13T15:34:59+00:00","description":"What to visit in Shawinigan? - La Cit\u00e9 de l'\u00e9nergie offers you a guided tour of Shawinigan aboard a tramway-style bus.","breadcrumb":{"@id":"https:\/\/www.citedelenergie.com\/en\/activites\/city-tour\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.citedelenergie.com\/en\/activites\/city-tour\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.citedelenergie.com\/en\/activites\/city-tour\/#primaryimage","url":"https:\/\/www.citedelenergie.com\/wp-content\/uploads\/2021\/06\/Tour-de-ville-1-scaled-1.jpg","contentUrl":"https:\/\/www.citedelenergie.com\/wp-content\/uploads\/2021\/06\/Tour-de-ville-1-scaled-1.jpg","width":1792,"height":1009,"caption":"Visite guid\u00e9e de la ville de Shawinigan \u00e0 bord d\u2019un autobus de style tramway (2)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.citedelenergie.com\/en\/activites\/city-tour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.citedelenergie.com\/en\/"},{"@type":"ListItem","position":2,"name":"City Tour"}]},{"@type":"WebSite","@id":"https:\/\/www.citedelenergie.com\/en\/#website","url":"https:\/\/www.citedelenergie.com\/en\/","name":"La Cit\u00e9 de l'\u00c9nergie","description":"Expositions &amp; Activit\u00e9s Immersives","publisher":{"@id":"https:\/\/www.citedelenergie.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.citedelenergie.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.citedelenergie.com\/en\/#organization","name":"La Cit\u00e9 de l'\u00c9nergie","url":"https:\/\/www.citedelenergie.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.citedelenergie.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.citedelenergie.com\/wp-content\/uploads\/2023\/04\/Logo-Cite-fond-mauve-2.png","contentUrl":"https:\/\/www.citedelenergie.com\/wp-content\/uploads\/2023\/04\/Logo-Cite-fond-mauve-2.png","width":762,"height":700,"caption":"La Cit\u00e9 de l'\u00c9nergie"},"image":{"@id":"https:\/\/www.citedelenergie.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/citedelenergie\/","https:\/\/x.com\/citedelenergie","https:\/\/www.instagram.com\/citedelenergie\/","https:\/\/www.youtube.com\/channel\/UCqe6ukCAPaHxd8osxT7eLIA"]}]}},"_links":{"self":[{"href":"https:\/\/www.citedelenergie.com\/en\/wp-json\/wp\/v2\/activites\/1777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.citedelenergie.com\/en\/wp-json\/wp\/v2\/activites"}],"about":[{"href":"https:\/\/www.citedelenergie.com\/en\/wp-json\/wp\/v2\/types\/activites"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.citedelenergie.com\/en\/wp-json\/wp\/v2\/media\/3040"}],"wp:attachment":[{"href":"https:\/\/www.citedelenergie.com\/en\/wp-json\/wp\/v2\/media?parent=1777"}],"wp:term":[{"taxonomy":"activites_categories","embeddable":true,"href":"https:\/\/www.citedelenergie.com\/en\/wp-json\/wp\/v2\/activites_categories?post=1777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}